{"id":67,"date":"2015-11-17T20:25:08","date_gmt":"2015-11-17T20:25:08","guid":{"rendered":"http:\/\/localhost:8888\/flatsome-next\/?page_id=3049"},"modified":"2020-09-21T06:53:25","modified_gmt":"2020-09-21T06:53:25","slug":"agency","status":"publish","type":"page","link":"https:\/\/demo.benova.com.my\/onlinestore2\/demos\/business-demos\/agency\/","title":{"rendered":"Agency"},"content":{"rendered":"\n  <div class=\"banner has-hover is-full-height has-parallax\" id=\"banner-1214914069\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-4\" data-parallax-container=\".banner\" data-parallax-background>\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"Portfolio\"  ><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1842836427\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n              <div data-parallax=\"-3\" data-parallax-fade=\"true\">       <div data-animate=\"fadeInUp\">           <div class=\"text-box-content text dark text-shadow-1\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1 class=\"uppercase\"><strong>WE&#8217;re a creative Agency<\/strong><\/h1>\n<p class=\"lead\">Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat<\/p>\n              <\/div>\n           <\/div>\n       <\/div>       <\/div>              \n<style>\n#text-box-1842836427 {\n  width: 100%;\n}\n#text-box-1842836427 .text-box-content {\n  font-size: 131%;\n}\n@media (min-width:550px) {\n  #text-box-1842836427 {\n    width: 59%;\n  }\n  #text-box-1842836427 .text-box-content {\n    font-size: 100%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1214914069 {\n  padding-top: 100%;\n}\n#banner-1214914069 .bg.bg-loaded {\n  background-image: url(https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-2.jpg);\n}\n#banner-1214914069 .overlay {\n  background-color: rgba(0, 0, 0, 0.27);\n}\n#banner-1214914069 .bg {\n  background-position: 49% 43%;\n}\n#banner-1214914069 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1214914069 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n  <div class=\"banner-grid-wrapper\">\n  <div id=\"banner-grid-102570255\" class=\"banner-grid row row-grid row-collapse row-full-width\" data-packery-options=\"\">\n                      \n<div class=\"col grid-col large-6 grid-col-2-3\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover bg-zoom\" id=\"banner-847511598\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"Portfolio\"  ><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1591451877\" class=\"text-box banner-layer x10 md-x10 lg-x10 y80 md-y80 lg-y80 res-text\">\n                     <div data-animate=\"fadeInRight\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-left\">\n                  \n<div class=\"video-button-wrapper\" style=\"font-size:130%\"><a href=\"https:\/\/www.youtube.com\/watch?v=f3Hh_qSkpaA\" class=\"button open-video icon circle is-outline is-xlarge\"><i class=\"icon-play\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\n<h3 class=\"uppercase\"><strong>This is a simple banner<\/strong><\/h3>\n<p class=\"lead\">A Website for Acme Company<\/p>\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-1591451877 {\n  width: 37%;\n}\n#text-box-1591451877 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-847511598 {\n  padding-top: 500px;\n}\n#banner-847511598 .bg.bg-loaded {\n  background-image: url(https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-2.jpg);\n}\n#banner-847511598 .overlay {\n  background-color: rgba(0, 0, 0, 0.2);\n}\n#banner-847511598 .bg {\n  background-position: 53% 69%;\n}\n#banner-847511598 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-847511598 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col large-6 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover bg-zoom\" id=\"banner-93278207\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"Portfolio\"  ><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-2110673741\" class=\"text-box banner-layer x90 md-x90 lg-x90 y50 md-y50 lg-y50 res-text\">\n                     <div data-animate=\"fadeInLeft\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-right\">\n                  \n<h3 class=\"uppercase\"><strong>This is a simple banner<\/strong><\/h3>\n<p class=\"lead\">A Website for Acme Company<\/p>\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-2110673741 {\n  width: 30%;\n}\n#text-box-2110673741 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-93278207 {\n  padding-top: 500px;\n}\n#banner-93278207 .bg.bg-loaded {\n  background-image: url(https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-2.jpg);\n}\n#banner-93278207 .overlay {\n  background-color: rgba(0, 0, 0, 0.19);\n}\n#banner-93278207 .bg {\n  background-position: 53% 69%;\n}\n#banner-93278207 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-93278207 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col large-3 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover bg-zoom\" id=\"banner-1593428249\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"Portfolio\"  ><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1728421158\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>This is a simple banner<\/strong><\/h3>\n<p class=\"lead\">A Website for Acme Company<\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1728421158 {\n  width: 60%;\n}\n#text-box-1728421158 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1593428249 {\n  padding-top: 500px;\n}\n#banner-1593428249 .bg.bg-loaded {\n  background-image: url(https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-2-300x195.jpg);\n}\n#banner-1593428249 .overlay {\n  background-color: rgba(0, 0, 0, 0.21);\n}\n#banner-1593428249 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1593428249 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col large-3 grid-col-1-2\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover bg-zoom\" id=\"banner-312965613\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"Portfolio\"  ><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1718117388\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n       <div class=\"hover-fade-out\">                         <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>This is a simple banner<\/strong><\/h3>\n<p class=\"lead\">A Website for Acme Company<\/p>\n              <\/div>\n           <\/div>\n                     <\/div>       \n<style>\n#text-box-1718117388 {\n  width: 60%;\n}\n#text-box-1718117388 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n   <div id=\"text-box-1203847878\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n       <div class=\"hover-zoom-in\">                         <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<div class=\"video-button-wrapper\" style=\"font-size:178%\"><a href=\"https:\/\/www.youtube.com\/watch?v=f3Hh_qSkpaA\" class=\"button open-video icon circle is-outline is-xlarge\"><i class=\"icon-play\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\n              <\/div>\n           <\/div>\n                     <\/div>       \n<style>\n#text-box-1203847878 {\n  width: 60%;\n}\n#text-box-1203847878 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-312965613 {\n  padding-top: 500px;\n}\n#banner-312965613 .bg.bg-loaded {\n  background-image: url(https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-2.jpg);\n}\n#banner-312965613 .overlay {\n  background-color: rgba(0, 0, 0, 0.47);\n}\n#banner-312965613 .bg {\n  background-position: 34% 46%;\n}\n#banner-312965613 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-312965613 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col large-6 grid-col-1-3\" ><div class=\"col-inner\">\n\n  <div class=\"banner has-hover bg-zoom\" id=\"banner-1936173408\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-151070776\" class=\"text-box banner-layer x10 md-x10 lg-x10 y70 md-y70 lg-y70 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-left\">\n                  \n<h3 class=\"uppercase\"><strong>This is a simple banner<\/strong><\/h3>\n<p class=\"lead\">A Website for Acme Company<\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-151070776 {\n  width: 39%;\n}\n#text-box-151070776 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1936173408 {\n  padding-top: 500px;\n}\n#banner-1936173408 .bg.bg-loaded {\n  background-image: url(https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-2.jpg);\n}\n#banner-1936173408 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#banner-1936173408 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n            <\/div>\n    <style>\n    #banner-grid-102570255 .grid-col-1{height: 885px}\n    #banner-grid-102570255 .grid-col-1-2{height: 442.5px}\n    #banner-grid-102570255 .grid-col-1-3{height:295px}\n    #banner-grid-102570255 .grid-col-2-3{height: 590px}\n    #banner-grid-102570255 .grid-col-1-4{height: 221.25px}\n    #banner-grid-102570255 .grid-col-3-4{height: 663.75px}\n\n\n    \n    \n\n  <\/style>\n    <\/div>\n  \n<div class=\"row\"  id=\"row-1461381842\">\n\n\t<div id=\"col-1255868657\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/elements\/pages\/portfolio\/\" target=\"_self\" class=\"button primary is-outline is-larger reveal-icon\"  style=\"border-radius:99px;\">\n    <span>Browse Portfolio<\/span>\n  <i class=\"icon-angle-right\" ><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Our Clients<\/span><b><\/b><\/h3><\/div>\n<div class=\"row align-middle row-dashed\"  id=\"row-1114855169\">\n\n\t<div id=\"col-1024079765\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 268.09523809524px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/themes\/flatsome\/assets\/img\/logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1444415583\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 268.09523809524px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/themes\/flatsome\/assets\/img\/logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1319547401\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 268.09523809524px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/themes\/flatsome\/assets\/img\/logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-531378009\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 268.09523809524px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/themes\/flatsome\/assets\/img\/logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1714854638\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 268.09523809524px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/themes\/flatsome\/assets\/img\/logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-346772009\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"ux-logo has-hover align-middle ux_logo inline-block\" style=\"max-width: 100%!important; width: 268.09523809524px!important\"><div class=\"ux-logo-link block image-color\" title=\"\"  href=\"\" style=\"padding: 15px;\"><img src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/themes\/flatsome\/assets\/img\/logo.png\" title=\"\" alt=\"\" class=\"ux-logo-image block\" style=\"height:50px;\" \/><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1533477922\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1533477922 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<section class=\"section\" id=\"section_857240678\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-center\"  id=\"row-1605271123\">\n\n\t<div id=\"col-303513542\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"uppercase\"><span style=\"font-size: 100%;\">Contact Us<\/span><\/h2>\n<p class=\"lead\">Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1656238255\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<div class=\"accordion\" rel=\"1\">\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>How long does it takes to we get back to you<\/span><\/a><div class=\"accordion-inner\">\n<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n<\/div><\/div>\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Accordion Panel<\/span><\/a><div class=\"accordion-inner\">\n<\/div><\/div>\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Add anything here<\/span><\/a><div class=\"accordion-inner\">\n<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n<\/div><\/div>\n<div class=\"accordion-item\"><a href=\"#\" class=\"accordion-title plain\"><button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\"><\/i><\/button><span>Research<\/span><\/a><div class=\"accordion-inner\">\n<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n<\/div><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1271399721\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>(insert contact form here)<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_857240678 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(207, 207, 207);\n}\n#section_857240678 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.85);\n}\n#section_857240678 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_857240678 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"container section-title-container\" style=\"margin-top:22px;\"><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">LAtest NEws<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-1 slider row-slider slider-nav-simple slider-nav-outside\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2020\/09\/30\/training-sport\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:180px;\">\n  \t\t\t\t\t\t\t<img width=\"559\" height=\"339\" src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2020\/09\/blog3.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">TRAINING SPORT<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetuer adipiscin\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Sep<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2020\/09\/30\/swimming-sport\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:180px;\">\n  \t\t\t\t\t\t\t<img width=\"559\" height=\"337\" src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2020\/09\/blog2.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">SWIMMING SPORT<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetuer adipiscin\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Sep<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2020\/09\/30\/running-sport\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:180px;\">\n  \t\t\t\t\t\t\t<img width=\"559\" height=\"339\" src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2020\/09\/blog1.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">RUNNING SPORT<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetuer adipiscin.\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Sep<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2020\/09\/21\/hello-world\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Hello world!<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">September 21, 2020<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Welcome to Benova Template Demo Sites. This is your first post. Edit or delete it,\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2015\/11\/19\/welcome-to-flatsome\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:180px;\">\n  \t\t\t\t\t\t\t<img width=\"300\" height=\"195\" src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Welcome to Flatsome<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Welcome to WordPress. This is your first post. Edit or delete it, then start blogging!\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">19<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2015\/10\/13\/velkommen-til-bloggen-min\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:180px;\">\n  \t\t\t\t\t\t\t<img width=\"300\" height=\"195\" src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Just another post with A Gallery<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetur adipiscing elit. In sed vulputate massa. Fusce ante magna,\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Oct<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2015\/10\/13\/a-simple-blog-post\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:180px;\">\n  \t\t\t\t\t\t\t<img width=\"300\" height=\"195\" src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">A Simple Blog Post<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Oct<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item has-post-icon\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/demo.benova.com.my\/onlinestore2\/2014\/01\/01\/a-video-blog-post\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-push box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:180px;\">\n  \t\t\t\t\t\t\t<img width=\"300\" height=\"195\" src=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/demo.benova.com.my\/onlinestore2\/wp-content\/uploads\/sites\/46\/2016\/08\/dummy-1.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\"><\/i>\n  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">A Video Blog Post<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetur adipiscing elit. In sed vulputate massa. Fusce ante magna,\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">01<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":12,"parent":69,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":[],"_links":{"self":[{"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/pages\/67"}],"collection":[{"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/comments?post=67"}],"version-history":[{"count":1,"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/pages\/67\/revisions"}],"predecessor-version":[{"id":137,"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/pages\/67\/revisions\/137"}],"up":[{"embeddable":true,"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/pages\/69"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/media\/12"}],"wp:attachment":[{"href":"https:\/\/demo.benova.com.my\/onlinestore2\/wp-json\/wp\/v2\/media?parent=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}