{"id":6,"date":"2020-09-21T06:52:18","date_gmt":"2020-09-21T06:52:18","guid":{"rendered":"https:\/\/demo.benova.com.my\/template12\/wishlist\/"},"modified":"2020-09-21T06:52:18","modified_gmt":"2020-09-21T06:52:18","slug":"wishlist","status":"publish","type":"page","link":"https:\/\/demo.benova.com.my\/template12\/wishlist\/","title":{"rendered":"Wishlist"},"content":{"rendered":"\n\n\n\n<form id=\"yith-wcwl-form\" action=\"https:\/\/demo.benova.com.my\/template12\/wishlist\/\" method=\"post\" class=\"woocommerce yith-wcwl-form wishlist-fragment\" data-fragment-options=\"{&quot;per_page&quot;:5,&quot;current_page&quot;:1,&quot;pagination&quot;:&quot;no&quot;,&quot;wishlist_id&quot;:false,&quot;action_params&quot;:false,&quot;no_interactions&quot;:false,&quot;layout&quot;:&quot;&quot;,&quot;wishlist&quot;:false,&quot;is_default&quot;:true,&quot;is_custom_list&quot;:false,&quot;wishlist_token&quot;:&quot;&quot;,&quot;is_private&quot;:false,&quot;count&quot;:0,&quot;page_title&quot;:&quot;My wishlist&quot;,&quot;default_wishlsit_title&quot;:&quot;My wishlist&quot;,&quot;page_links&quot;:false,&quot;is_user_logged_in&quot;:false,&quot;is_user_owner&quot;:true,&quot;can_user_edit_title&quot;:false,&quot;show_price&quot;:false,&quot;show_dateadded&quot;:false,&quot;show_stock_status&quot;:false,&quot;show_add_to_cart&quot;:false,&quot;show_remove_product&quot;:true,&quot;add_to_cart_text&quot;:&quot;Add to cart&quot;,&quot;show_ask_estimate_button&quot;:false,&quot;ask_estimate_url&quot;:&quot;&quot;,&quot;price_excl_tax&quot;:true,&quot;show_cb&quot;:false,&quot;show_quantity&quot;:false,&quot;show_variation&quot;:false,&quot;show_price_variations&quot;:false,&quot;show_update&quot;:false,&quot;enable_drag_n_drop&quot;:false,&quot;enable_add_all_to_cart&quot;:false,&quot;move_to_another_wishlist&quot;:false,&quot;repeat_remove_button&quot;:false,&quot;show_last_column&quot;:false,&quot;heading_icon&quot;:&quot;&lt;i class=\\&quot;fa fa-heart-o\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;share_enabled&quot;:false,&quot;template_part&quot;:&quot;view&quot;,&quot;additional_info&quot;:false,&quot;available_multi_wishlist&quot;:false,&quot;form_action&quot;:&quot;https:\\\/\\\/demo.benova.com.my\\\/template12\\\/wishlist\\\/&quot;,&quot;item&quot;:&quot;wishlist&quot;}\">\n\n\t<!-- TITLE -->\n\t\t\t\t<div class=\"wishlist-title \">\n\t\t\t<h2>My wishlist<\/h2>\t\t\t\t\t<\/div>\n\t\t\t\t\n\n<!-- WISHLIST TABLE -->\n<table\n\tclass=\"shop_table cart wishlist_table wishlist_view traditional responsive   \"\n\tdata-pagination=\"no\" data-per-page=\"5\"\n\tdata-page=\"1\" data-id=\"\"\n\tdata-token=\"\">\n\n\t\n\t<thead>\n\t<tr>\n\t\t\n\t\t\t\t\t\t\t\t<th class=\"product-remove\">\n\t\t\t\t<span class=\"nobr\">\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/th>\n\t\t\n\t\t<th class=\"product-thumbnail\"><\/th>\n\n\t\t<th class=\"product-name\">\n\t\t\t<span class=\"nobr\">\n\t\t\t\tProduct name\t\t\t<\/span>\n\t\t<\/th>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/tr>\n\t<\/thead>\n\n\t<tbody class=\"wishlist-items-wrapper\">\n\t\t\t<tr>\n\t\t\t<td colspan=\"3\" class=\"wishlist-empty\">No products added to the wishlist<\/td>\n\t\t<\/tr>\n\t\t<\/tbody>\n\n<\/table>\n\n\t<div class=\"yith_wcwl_wishlist_footer\">\n\t\t\n\n\t\t\n\n\t\t\n\t\t\t<\/div>\n\n\t<input type=\"hidden\" id=\"yith_wcwl_edit_wishlist\" name=\"yith_wcwl_edit_wishlist\" value=\"442bf78fbb\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/template12\/wp-json\/wp\/v2\/pages\/6\" \/>\t<input type=\"hidden\" value=\"\" name=\"wishlist_id\" id=\"wishlist_id\">\n\n\t\n<\/form>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wishlist - Template 12<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wishlist - Template 12\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demo.benova.com.my\/template12\/wishlist\/\" \/>\n<meta property=\"og:site_name\" content=\"Template 12\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/demo.benova.com.my\/template12\/wishlist\/\",\"url\":\"https:\/\/demo.benova.com.my\/template12\/wishlist\/\",\"name\":\"Wishlist - Template 12\",\"isPartOf\":{\"@id\":\"https:\/\/demo.benova.com.my\/template12\/#website\"},\"datePublished\":\"2020-09-21T06:52:18+00:00\",\"dateModified\":\"2020-09-21T06:52:18+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/demo.benova.com.my\/template12\/wishlist\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/demo.benova.com.my\/template12\/#website\",\"url\":\"https:\/\/demo.benova.com.my\/template12\/\",\"name\":\"Template 12\",\"description\":\"Just another Benova Template Demo Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/demo.benova.com.my\/template12\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wishlist - Template 12","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Wishlist - Template 12","og_url":"https:\/\/demo.benova.com.my\/template12\/wishlist\/","og_site_name":"Template 12","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/demo.benova.com.my\/template12\/wishlist\/","url":"https:\/\/demo.benova.com.my\/template12\/wishlist\/","name":"Wishlist - Template 12","isPartOf":{"@id":"https:\/\/demo.benova.com.my\/template12\/#website"},"datePublished":"2020-09-21T06:52:18+00:00","dateModified":"2020-09-21T06:52:18+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/demo.benova.com.my\/template12\/wishlist\/"]}]},{"@type":"WebSite","@id":"https:\/\/demo.benova.com.my\/template12\/#website","url":"https:\/\/demo.benova.com.my\/template12\/","name":"Template 12","description":"Just another Benova Template Demo Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demo.benova.com.my\/template12\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/demo.benova.com.my\/template12\/wp-json\/wp\/v2\/pages\/6"}],"collection":[{"href":"https:\/\/demo.benova.com.my\/template12\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.benova.com.my\/template12\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.benova.com.my\/template12\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.benova.com.my\/template12\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":0,"href":"https:\/\/demo.benova.com.my\/template12\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.benova.com.my\/template12\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}